{"id":40837,"date":"2023-07-28T17:31:39","date_gmt":"2023-07-28T15:31:39","guid":{"rendered":"https:\/\/www.jklas.cz\/produkty\/elektricke-tahace\/jkl\/tahac-bull-5-4w-pro-sediciho-ridice\/"},"modified":"2023-08-03T13:39:44","modified_gmt":"2023-08-03T11:39:44","slug":"bull-7e","status":"publish","type":"page","link":"https:\/\/www.jklas.cz\/sk\/produkty\/elektricke-tahace\/dec\/bull-7e\/","title":{"rendered":"Taha\u010d BULL 7E pro sed\u00edc\u00edho \u0159idi\u010de"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;15px||||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;90%&#8220; width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;40672&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;fa-solid900||||||||&#8220; text_line_height=&#8220;1.2em&#8220; link_font=&#8220;||||on|||#000000|solid&#8220; custom_margin=&#8220;0px||0px|0px|false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<nav>\n<p style=\"font-size: 18px; color: #fecc00;\">\uf015 <a href=\"https:\/\/www.jklas.cz\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">\u00davod<\/span><\/a> \uf105 <a href=\"https:\/\/www.jklas.cz\/produkty\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">Produkty<\/span><\/a> \uf105 <a href=\"https:\/\/www.jklas.cz\/produkty\/elektricke-tahace\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">Elektrick\u00e9 taha\u010de<\/span><\/a> \uf105 <a href=\"https:\/\/www.jklas.cz\/produkty\/elektricke-tahace\/jkl\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">Do 25t<\/span><\/a><\/p>\n<\/nav>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;3_4,1_4&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.16&#8243; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;2em&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;18px&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; custom_padding_tablet=&#8220;||||false|false&#8220; custom_padding_phone=&#8220;15px||0px||false|false&#8220; custom_padding_last_edited=&#8220;off|desktop&#8220; header_text_align_tablet=&#8220;center&#8220; header_text_align_phone=&#8220;center&#8220; header_text_align_last_edited=&#8220;on|desktop&#8220; border_color_all=&#8220;#adadad&#8220; border_width_bottom=&#8220;1px&#8220; border_color_bottom=&#8220;#fecc00&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Elektrick\u00fd taha\u010d <span style=\"color: #fecc00;\">BULL 7E<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;0px||60px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dsm_image_carousel gallery_ids=&#8220;40853,40854,40855,40856&#8243; slide_to_show=&#8220;1&#8243; speed=&#8220;1000&#8243; pause_on_hover=&#8220;on&#8220; space_between=&#8220;0&#8243; arrow_position_mobile=&#8220;outside&#8220; arrow_size=&#8220;50px&#8220; dots=&#8220;off&#8220; show_lightbox=&#8220;on&#8220; show_lightbox_gallery=&#8220;on&#8220; arrow_color=&#8220;#fecc00&#8243; arrow_background_color=&#8220;RGBA(255,255,255,0)&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;65%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||-20px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/dsm_image_carousel][et_pb_video src=&#8220;https:\/\/youtu.be\/cgzHGdJdmV0&#8243; _builder_version=&#8220;4.21.0&#8243; custom_margin=&#8220;30px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; border_width_all=&#8220;3px&#8220; border_color_all=&#8220;#fecc00&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_video][et_pb_video src=&#8220;https:\/\/youtu.be\/-wPHSaz5l9g&#8220; _builder_version=&#8220;4.21.0&#8243; custom_margin=&#8220;30px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; border_width_all=&#8220;3px&#8220; border_color_all=&#8220;#fecc00&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_video][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;2.2em&#8220; link_font=&#8220;|700|||on|||#14a800|&#8220; link_text_color=&#8220;#14a800&#8243; header_2_font=&#8220;|600|||||||&#8220; header_2_text_color=&#8220;#000000&#8243; header_2_font_size=&#8220;16px&#8220; background_color=&#8220;rgba(254,204,0,0.1)&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;10px||0px||false|false&#8220; custom_padding=&#8220;25px||10px||false|false&#8220; border_radii=&#8220;off|20px|20px||&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;rgba(254,204,0,0.4)&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Z\u00e1kladn\u00ed informace<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;2em&#8220; link_font=&#8220;||||on|||#ff3333|&#8220; link_text_color=&#8220;#ff3333&#8243; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;15px|30px|15px|30px|false|false&#8220; border_radii=&#8220;off|||10px|10px&#8220; border_width_right=&#8220;1px&#8220; border_color_right=&#8220;rgba(254,204,0,0.4)&#8220; border_width_bottom=&#8220;1px&#8220; border_color_bottom=&#8220;rgba(254,204,0,0.4)&#8220; border_width_left=&#8220;1px&#8220; border_color_left=&#8220;rgba(254,204,0,0.4)&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>Elektrick\u00fd taha\u010d pro sed\u00edc\u00edho \u0159idi\u010de BULL 7E slou\u017e\u00ed k manipulaci n\u00e1kladu a\u017e do 7 tun.<\/strong> Je v\u00fdkonn\u00fd, ergonomick\u00fd a n\u00edzko polo\u017een\u00fd pro snadn\u00e9 nastupov\u00e1n\u00ed\/vystupov\u00e1n\u00ed. <strong>Hod\u00ed se pro vnit\u0159n\u00ed i venkovn\u00ed pou\u017eit\u00ed.<\/strong> <strong>Taha\u010d lze vybavit \u0161irokou \u0161k\u00e1lou p\u0159\u00edslu\u0161enstv\u00ed<\/strong> \u2013 nap\u0159. bezp. osv\u011btlen\u00ed, kabina pro \u0159idi\u010de, st\u011bra\u010de a mnoho dal\u0161\u00edho (viz video).<strong> S konfigurac\u00ed stroje V\u00e1m r\u00e1di pom\u016f\u017eeme.<\/strong> Kabina m\u016f\u017ee b\u00fdt bu\u010f otev\u0159en\u00e1 (bez dve\u0159\u00ed) nebo lehk\u00e1 (PVC) nebo robustn\u00ed kovov\u00e1. Interaktivn\u00ed displej ukazuje stav baterie, rychlost apod. Taha\u010d je standardn\u011b <strong>vybaven trak\u010dn\u00ed bateri\u00ed, <\/strong>jej\u00ed\u017e v\u00fdm\u011bna m\u016f\u017ee b\u00fdt provedena vertik\u00e1ln\u011b i horizont\u00e1ln\u011b. <strong>Pro v\u00edce informac\u00ed o taha\u010di, n\u00e1s pros\u00edm kontaktujte.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;mt|center_focus_strong|&#xe3b4;||fa||400&#8243; icon_color=&#8220;#fecc00&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;26px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;||||||||&#8220; body_text_color=&#8220;#000000&#8243; body_line_height=&#8220;1.8em&#8220; body_link_font=&#8220;||||on||||&#8220; body_link_text_color=&#8220;#161180&#8243; custom_margin=&#8220;10px|0px|0px|0px|false|false&#8220; custom_padding=&#8220;5px|0px|0px|5px|false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;padding-right: 10px;&#8220; icon_font_size=&#8220;26px&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Dopl\u0148kov\u00e1 v\u00fdbava (na p\u0159\u00e1n\u00ed): kabina bez dve\u0159\u00ed (otev\u0159en\u00e1), kabina PVC, kabina kovov\u00e1, vyt\u00e1p\u011bn\u00ed kabiny, \u010deln\u00ed sklo, st\u011bra\u010de, zp\u011btn\u00e1 zrc\u00e1tka, bezp. maj\u00e1k, modr\u00e9 sv\u011btlo, nezna\u010d\u00edc\u00ed kola, tla\u010d\u00edtka pro manu\u00e1ln\u00ed pojezd vp\u0159ed\/vzad, set pro v\u00fdm\u011bnu baterie, a dal\u0161\u00ed&#8230;<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;mt|reply_all|&#xe15f;||fa||400&#8243; icon_color=&#8220;#fecc00&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;26px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;||||||||&#8220; body_text_color=&#8220;#000000&#8243; body_line_height=&#8220;1.8em&#8220; body_link_font=&#8220;||||on||||&#8220; body_link_text_color=&#8220;#161180&#8243; custom_margin=&#8220;0px|0px|0px|0px|false|false&#8220; custom_padding=&#8220;5px|0px|0px|5px|false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;padding-right: 10px;&#8220; icon_font_size=&#8220;26px&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Vertik\u00e1ln\u00ed i horizont\u00e1ln\u00ed v\u00fdm\u011bna baterie<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;mt|done_all|&#xe877;||fa||400&#8243; icon_color=&#8220;#fecc00&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;26px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;||||||||&#8220; body_text_color=&#8220;#000000&#8243; body_line_height=&#8220;1.8em&#8220; body_link_font=&#8220;||||on||||&#8220; body_link_text_color=&#8220;#161180&#8243; custom_margin=&#8220;0px|0px|0px|0px|false|false&#8220; custom_padding=&#8220;5px|0px|0px|5px|false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;padding-right: 10px;&#8220; icon_font_size=&#8220;26px&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Pro vnit\u0159n\u00ed i venkovn\u00ed pou\u017eit\u00ed<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb url=&#8220;https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/Elektricke-tahace-do-25t-CZ-prezentace.pdf&#8220; url_new_window=&#8220;on&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#xf1c1;||fa||900&#8243; icon_color=&#8220;#14a800&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;24px&#8220; content_max_width=&#8220;100%&#8220; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;|700|||on||||&#8220; body_text_color=&#8220;#14a800&#8243; body_link_font=&#8220;||||||||&#8220; body_link_text_color=&#8220;#161180&#8243; background_color=&#8220;rgba(20,168,0,0.05)&#8220; width=&#8220;100%&#8220; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;15px||15px|15%|false|false&#8220; animation=&#8220;off&#8220; link_option_url=&#8220;https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/Elektricke-tahace-do-25t-CZ-prezentace.pdf&#8220; link_option_url_new_window=&#8220;on&#8220; custom_css_blurb_image=&#8220;padding-right: 25px;&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;rgba(20,168,0,0.3)&#8220; icon_font_size=&#8220;24px&#8220; global_module=&#8220;40775&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; background_color__hover=&#8220;#14a800&#8243; background_enable_color__hover=&#8220;on&#8220; icon_color__hover_enabled=&#8220;on|hover&#8220; icon_color__hover=&#8220;#ffffff&#8220; body_text_color__hover_enabled=&#8220;on|hover&#8220; body_text_color__hover=&#8220;#ffffff&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|hover&#8220; transform_rotate__hover_enabled=&#8220;on|hover&#8220; transform_skew__hover_enabled=&#8220;on|hover&#8220; transform_origin__hover_enabled=&#8220;on|hover&#8220; background__hover_enabled=&#8220;on|hover&#8220;]<\/p>\n<p>Prezentace &#8211; elektrick\u00e9 taha\u010de do 25t (CZ)<\/p>\n<p>[\/et_pb_blurb][et_pb_text disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;||on||||||&#8220; text_text_color=&#8220;#000000&#8243; text_orientation=&#8220;center&#8220; custom_margin=&#8220;5px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; background_color_gradient_stops_tablet=&#8220;#2b87da 0%|#29c4a9 100%&#8220; background_color_gradient_stops_phone=&#8220;#2b87da 0%|#29c4a9 100%&#8220; global_module=&#8220;40776&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>\u201eProhl\u00e9dn\u011bte si PDF prezentaci na\u0161ich taha\u010d\u016f \u2013 obsahuje p\u0159ehled model\u016f, fotky a dal\u0161\u00ed u\u017eite\u010dn\u00e9 informace.\u201c<\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#d6d6d6&#8243; divider_position=&#8220;center&#8220; divider_weight=&#8220;1px&#8220; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.9.3&#8243; _module_preset=&#8220;default&#8220; width=&#8220;75%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;5px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;36180&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQwNjc5In19@&#8220; button_text=&#8220;Cenov\u00e1 nab\u00eddka&#8220; button_alignment=&#8220;center&#8220; disabled_on=&#8220;on|on|off&#8220; module_id=&#8220;cenova-nabidka&#8220; _builder_version=&#8220;4.21.0&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#1613d6&#8243; button_border_width=&#8220;1px&#8220; button_border_color=&#8220;#0c007f&#8220; button_border_radius=&#8220;24px&#8220; button_font=&#8220;|700|||||||&#8220; button_icon=&#8220;mt|swap_vert|&#xe8d5;||fa||400&#8243; button_icon_placement=&#8220;left&#8220; button_on_hover=&#8220;off&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;7px|21px|6px|42px|false|false&#8220; custom_css_main_element=&#8220;width: 50%&#8220; global_module=&#8220;40700&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220;][\/et_pb_button][et_pb_text disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.8em&#8220; text_orientation=&#8220;center&#8220; width=&#8220;75%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;40701&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><em>&#8222;P\u0159ejete si zaslat cenovou nab\u00eddku na n\u00e1\u0161 taha\u010d?&#8220;<\/em><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.6em&#8220; link_font=&#8220;||||on|||#ff3333|&#8220; link_text_color=&#8220;#ff3333&#8243; header_2_font=&#8220;|600|||||||&#8220; header_2_text_color=&#8220;#000000&#8243; header_2_font_size=&#8220;16px&#8220; header_2_line_height=&#8220;0.4em&#8220; background_color=&#8220;rgba(254,204,0,0.1)&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;30px||10px||false|false&#8220; border_radii=&#8220;off|20px|20px||&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;rgba(254,204,0,0.4)&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Technick\u00e9 \u00fadaje<em><\/em><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;2em&#8220; link_font=&#8220;|700|||on|||#ff3333|&#8220; link_text_color=&#8220;#ff3333&#8243; text_orientation=&#8220;justified&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;15px|30px|0px|30px|false|false&#8220; hover_enabled=&#8220;0&#8243; border_radii=&#8220;off|||10px|10px&#8220; border_width_right=&#8220;1px&#8220; border_color_right=&#8220;rgba(254,204,0,0.4)&#8220; border_width_bottom=&#8220;1px&#8220; border_color_bottom=&#8220;rgba(254,204,0,0.4)&#8220; border_width_left=&#8220;1px&#8220; border_color_left=&#8220;rgba(254,204,0,0.4)&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<table style=\"width: 100%; border: none;\">\n<tbody>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>V\u00fdkon:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\">5000 W, AC<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Ta\u017en\u00e1 s\u00edla:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\">a\u017e 7000 kg<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Baterie:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>48 V, 300 Ah<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Max. rychlost:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>14 km\/h, nastaviteln\u00e1<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Kola (p\u0159edn\u00ed\/zadn\u00ed)<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>1 \/ 2x<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Typ kol:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>superelastick\u00e1, \u00f8 380 \/ 404 mm <\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Hmotnost:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>1000 kg (v\u010d. baterie)<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Rozm\u011bry:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>965 x 2025 x 750 mm<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Sv\u011btl\u00e1 v\u00fd\u0161ka:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>100 mm<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; disabled_on=&#8220;off|off|on&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;15px||||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width_tablet=&#8220;90%&#8220; width_phone=&#8220;90%&#8220; width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;40672&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;fa-solid900||||||||&#8220; text_line_height=&#8220;1.2em&#8220; link_font=&#8220;||||on|||#000000|solid&#8220; custom_margin=&#8220;0px||0px|0px|false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<nav>\n<p style=\"font-size: 18px; color: #fecc00;\">\uf015 <a href=\"https:\/\/www.jklas.cz\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">\u00davod<\/span><\/a> \uf105 <a href=\"https:\/\/www.jklas.cz\/produkty\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">Produkty<\/span><\/a> \uf105 <a href=\"https:\/\/www.jklas.cz\/produkty\/elektricke-tahace\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">Elektrick\u00e9 taha\u010de<\/span><\/a> \uf105 <a href=\"https:\/\/www.jklas.cz\/produkty\/elektricke-tahace\/jkl\/\"><span style=\"font-size: 14px; color: black; font-family: Open Sans;\">Do 25t<\/span><\/a><\/p>\n<\/nav>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.16&#8243; width=&#8220;90%&#8220; width_tablet=&#8220;90%&#8220; width_last_edited=&#8220;off|phone&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_css_main_element=&#8220;width: 70%!important;||margin-bottom: 0px;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;2em&#8220; header_font=&#8220;|700|||||||&#8220; header_text_align=&#8220;left&#8220; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;16px&#8220; header_line_height=&#8220;1.6em&#8220; text_orientation=&#8220;center&#8220; width=&#8220;100%&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; custom_padding_tablet=&#8220;20px||||false|false&#8220; custom_padding_phone=&#8220;0px||||false|false&#8220; custom_padding_last_edited=&#8220;on|tablet&#8220; border_color_all=&#8220;#adadad&#8220; border_width_bottom=&#8220;1px&#8220; border_color_bottom=&#8220;#fecc00&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Elektrick\u00fd taha\u010d <span style=\"color: #fecc00;\">BULL 7E<\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; custom_css_main_element=&#8220;width: 30%!important;||margin-bottom: 0px;&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=&#8220;off|off|off&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;15px||60px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dsm_image_carousel gallery_ids=&#8220;40853,40854,40855,40856&#8243; slide_to_show=&#8220;1&#8243; speed=&#8220;1000&#8243; pause_on_hover=&#8220;on&#8220; space_between=&#8220;0&#8243; arrow_position_mobile=&#8220;outside&#8220; arrow_size=&#8220;50px&#8220; dots=&#8220;off&#8220; show_lightbox=&#8220;on&#8220; show_lightbox_gallery=&#8220;on&#8220; arrow_color=&#8220;#fecc00&#8243; arrow_background_color=&#8220;RGBA(255,255,255,0)&#8220; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;65%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||-20px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/dsm_image_carousel][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;2.2em&#8220; link_font=&#8220;|700|||on|||#14a800|&#8220; link_text_color=&#8220;#14a800&#8243; header_2_font=&#8220;|600|||||||&#8220; header_2_text_color=&#8220;#000000&#8243; header_2_font_size=&#8220;16px&#8220; background_color=&#8220;rgba(254,204,0,0.1)&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;15px||0px||false|false&#8220; border_radii=&#8220;off|10px|10px||&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;rgba(254,204,0,0.4)&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Z\u00e1kladn\u00ed informace<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.8em&#8220; link_font=&#8220;||||on|||#ff3333|&#8220; link_text_color=&#8220;#ff3333&#8243; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;7px|15px|7px|15px|false|false&#8220; border_radii=&#8220;off|||10px|10px&#8220; border_width_right=&#8220;1px&#8220; border_color_right=&#8220;rgba(254,204,0,0.4)&#8220; border_width_bottom=&#8220;1px&#8220; border_color_bottom=&#8220;rgba(254,204,0,0.4)&#8220; border_width_left=&#8220;1px&#8220; border_color_left=&#8220;rgba(254,204,0,0.4)&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>Elektrick\u00fd taha\u010d pro sed\u00edc\u00edho \u0159idi\u010de BULL 7E slou\u017e\u00ed k manipulaci n\u00e1kladu a\u017e do 7 tun.<\/strong> Je v\u00fdkonn\u00fd, ergonomick\u00fd a n\u00edzko polo\u017een\u00fd pro snadn\u00e9 nastupov\u00e1n\u00ed\/vystupov\u00e1n\u00ed. <strong>Hod\u00ed se pro vnit\u0159n\u00ed i venkovn\u00ed pou\u017eit\u00ed.<\/strong> <strong>Taha\u010d lze vybavit \u0161irokou \u0161k\u00e1lou p\u0159\u00edslu\u0161enstv\u00ed<\/strong> \u2013 nap\u0159. bezp. osv\u011btlen\u00ed, kabina pro \u0159idi\u010de, st\u011bra\u010de a mnoho dal\u0161\u00edho (viz video).<strong> S konfigurac\u00ed stroje V\u00e1m r\u00e1di pom\u016f\u017eeme.<\/strong> Kabina m\u016f\u017ee b\u00fdt bu\u010f otev\u0159en\u00e1 (bez dve\u0159\u00ed) nebo lehk\u00e1 (PVC) nebo robustn\u00ed kovov\u00e1. Interaktivn\u00ed displej ukazuje stav baterie, rychlost apod. Taha\u010d je standardn\u011b <strong>vybaven trak\u010dn\u00ed bateri\u00ed, <\/strong>jej\u00ed\u017e v\u00fdm\u011bna m\u016f\u017ee b\u00fdt provedena vertik\u00e1ln\u011b i horizont\u00e1ln\u011b. <strong>Pro v\u00edce informac\u00ed o taha\u010di, n\u00e1s pros\u00edm kontaktujte.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_video src=&#8220;https:\/\/youtu.be\/cgzHGdJdmV0&#8243; _builder_version=&#8220;4.21.0&#8243; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; border_width_all=&#8220;3px&#8220; border_color_all=&#8220;#fecc00&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_video][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;mt|center_focus_strong|&#xe3b4;||fa||400&#8243; icon_color=&#8220;#fecc00&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;26px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;||||||||&#8220; body_text_color=&#8220;#000000&#8243; body_line_height=&#8220;1.8em&#8220; body_link_font=&#8220;||||on||||&#8220; body_link_text_color=&#8220;#161180&#8243; custom_margin=&#8220;10px|0px|0px|0px|false|false&#8220; custom_padding=&#8220;5px|0px|0px|5px|false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;padding-right: 10px;&#8220; icon_font_size=&#8220;26px&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Dopl\u0148kov\u00e1 v\u00fdbava (na p\u0159\u00e1n\u00ed): kabina bez dve\u0159\u00ed (otev\u0159en\u00e1), kabina PVC, kabina kovov\u00e1, vyt\u00e1p\u011bn\u00ed kabiny, \u010deln\u00ed sklo, st\u011bra\u010de, zp\u011btn\u00e1 zrc\u00e1tka, bezp. maj\u00e1k, modr\u00e9 sv\u011btlo, nezna\u010d\u00edc\u00ed kola, tla\u010d\u00edtka pro manu\u00e1ln\u00ed pojezd vp\u0159ed\/vzad, set pro v\u00fdm\u011bnu baterie, a dal\u0161\u00ed&#8230;<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;mt|reply_all|&#xe15f;||fa||400&#8243; icon_color=&#8220;#fecc00&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;26px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;||||||||&#8220; body_text_color=&#8220;#000000&#8243; body_line_height=&#8220;1.8em&#8220; body_link_font=&#8220;||||on||||&#8220; body_link_text_color=&#8220;#161180&#8243; custom_margin=&#8220;0px|0px|0px|0px|false|false&#8220; custom_padding=&#8220;5px|0px|0px|5px|false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;padding-right: 10px;&#8220; icon_font_size=&#8220;26px&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Vertik\u00e1ln\u00ed i horizont\u00e1ln\u00ed v\u00fdm\u011bna baterie<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8220;on&#8220; font_icon=&#8220;mt|done_all|&#xe877;||fa||400&#8243; icon_color=&#8220;#fecc00&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;26px&#8220; content_max_width=&#8220;100%&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;||||||||&#8220; body_text_color=&#8220;#000000&#8243; body_line_height=&#8220;1.8em&#8220; body_link_font=&#8220;||||on||||&#8220; body_link_text_color=&#8220;#161180&#8243; custom_margin=&#8220;0px|0px|0px|0px|false|false&#8220; custom_padding=&#8220;5px|0px|0px|5px|false|false&#8220; animation=&#8220;off&#8220; custom_css_blurb_image=&#8220;padding-right: 10px;&#8220; icon_font_size=&#8220;26px&#8220; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Pro vnit\u0159n\u00ed i venkovn\u00ed pou\u017eit\u00ed<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb url=&#8220;https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/Elektricke-tahace-do-25t-CZ-prezentace.pdf&#8220; url_new_window=&#8220;on&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#xf1c1;||fa||900&#8243; icon_color=&#8220;#14a800&#8243; icon_placement=&#8220;left&#8220; image_icon_width=&#8220;24px&#8220; content_max_width=&#8220;100%&#8220; disabled_on=&#8220;off|off|on&#8220; _builder_version=&#8220;4.21.0&#8243; header_level=&#8220;h2&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;14px&#8220; header_line_height=&#8220;1.8em&#8220; body_font=&#8220;|700|||on||||&#8220; body_text_color=&#8220;#14a800&#8243; body_link_font=&#8220;||||||||&#8220; body_link_text_color=&#8220;#161180&#8243; background_color=&#8220;rgba(20,168,0,0.05)&#8220; width=&#8220;100%&#8220; custom_margin=&#8220;15px||0px|0px|false|false&#8220; custom_padding=&#8220;15px||15px|10%|false|false&#8220; animation=&#8220;off&#8220; link_option_url=&#8220;https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/Elektricke-tahace-do-25t-CZ-prezentace.pdf&#8220; link_option_url_new_window=&#8220;on&#8220; border_radii=&#8220;on|15px|15px|15px|15px&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;rgba(20,168,0,0.3)&#8220; icon_font_size=&#8220;24px&#8220; global_module=&#8220;40777&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; background_color__hover=&#8220;#14a800&#8243; background_enable_color__hover=&#8220;on&#8220; icon_color__hover_enabled=&#8220;on|hover&#8220; icon_color__hover=&#8220;#ffffff&#8220; body_text_color__hover_enabled=&#8220;on|hover&#8220; body_text_color__hover=&#8220;#ffffff&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|hover&#8220; transform_rotate__hover_enabled=&#8220;on|hover&#8220; transform_skew__hover_enabled=&#8220;on|hover&#8220; transform_origin__hover_enabled=&#8220;on|hover&#8220; background__hover_enabled=&#8220;on|hover&#8220;]<\/p>\n<p>Prezentace &#8211; elektrick\u00e9 taha\u010de do 25t (CZ)<\/p>\n<p>[\/et_pb_blurb][et_pb_text disabled_on=&#8220;off|off|on&#8220; _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;||on||||||&#8220; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.6em&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;5px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;40778&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span>\u201eProhl\u00e9dn\u011bte si PDF prezentaci na\u0161ich taha\u010d\u016f \u2013 obsahuje p\u0159ehled model\u016f, fotky a dal\u0161\u00ed u\u017eite\u010dn\u00e9 informace.\u201c<\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#d6d6d6&#8243; divider_position=&#8220;center&#8220; divider_weight=&#8220;1px&#8220; _builder_version=&#8220;4.9.3&#8243; _module_preset=&#8220;default&#8220; width=&#8220;80%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;5px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;37406&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][et_pb_button button_url=&#8220;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQwNjc5In19@&#8220; button_text=&#8220;Cenov\u00e1 nab\u00eddka&#8220; button_alignment=&#8220;center&#8220; module_id=&#8220;cenova-nabidka&#8220; _builder_version=&#8220;4.21.0&#8243; _dynamic_attributes=&#8220;button_url&#8220; _module_preset=&#8220;default&#8220; custom_button=&#8220;on&#8220; button_text_size=&#8220;14px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#1613d6&#8243; button_border_width=&#8220;1px&#8220; button_border_color=&#8220;#140f9b&#8220; button_border_radius=&#8220;24px&#8220; button_font=&#8220;|700|||||||&#8220; button_icon=&#8220;mt|swap_vert|&#xe8d5;||fa||400&#8243; button_icon_placement=&#8220;left&#8220; button_on_hover=&#8220;off&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;7px||6px|40px|false|false&#8220; custom_css_main_element=&#8220;width: 75%&#8220; global_module=&#8220;40684&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; transform_styles__hover_enabled=&#8220;on|hover&#8220; transform_scale__hover_enabled=&#8220;on|hover&#8220; transform_translate__hover_enabled=&#8220;on|desktop&#8220; transform_rotate__hover_enabled=&#8220;on|desktop&#8220; transform_skew__hover_enabled=&#8220;on|desktop&#8220; transform_origin__hover_enabled=&#8220;on|desktop&#8220; transform_scale__hover=&#8220;105%|105%&#8220;][\/et_pb_button][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.6em&#8220; text_orientation=&#8220;center&#8220; width=&#8220;90%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;3px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_module=&#8220;40699&#8243; saved_tabs=&#8220;all&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><em>&#8222;P\u0159ejete si zaslat cenovou nab\u00eddku na n\u00e1\u0161 taha\u010d?&#8220;<\/em><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_font=&#8220;||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.6em&#8220; link_font=&#8220;||||on|||#ff3333|&#8220; link_text_color=&#8220;#ff3333&#8243; header_2_font=&#8220;|600|||||||&#8220; header_2_text_color=&#8220;#000000&#8243; header_2_font_size=&#8220;16px&#8220; header_2_line_height=&#8220;0.4em&#8220; background_color=&#8220;rgba(254,204,0,0.1)&#8220; text_orientation=&#8220;center&#8220; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;25px|3%|10px|3%|false|false&#8220; border_radii=&#8220;off|20px|20px||&#8220; border_width_all=&#8220;1px&#8220; border_color_all=&#8220;rgba(254,204,0,0.4)&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Technick\u00e9 \u00fadaje<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.21.0&#8243; text_text_color=&#8220;#000000&#8243; text_line_height=&#8220;1.6em&#8220; link_font=&#8220;|700|||on|||#ffb600|&#8220; link_text_color=&#8220;#ffb600&#8243; text_orientation=&#8220;justified&#8220; width=&#8220;100%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;10px|15px|0px|15px|false|false&#8220; border_radii=&#8220;off|||10px|10px&#8220; border_width_right=&#8220;1px&#8220; border_color_right=&#8220;rgba(254,204,0,0.4)&#8220; border_width_bottom=&#8220;1px&#8220; border_color_bottom=&#8220;rgba(254,204,0,0.4)&#8220; border_width_left=&#8220;1px&#8220; border_color_left=&#8220;rgba(254,204,0,0.4)&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<table style=\"width: 100%; border: none;\">\n<tbody>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>V\u00fdkon:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\">5000 W, AC<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Ta\u017en\u00e1 s\u00edla:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\">a\u017e 7000 kg<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Baterie:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>48 V, 300 Ah<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Max. rychlost:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>14 km\/h, nastaviteln\u00e1<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Kola (p\u0159edn\u00ed\/zadn\u00ed)<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>1 \/ 2x<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Typ kol:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>superelastick\u00e1, \u00f8 380 \/ 404 mm <\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Hmotnost:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>1000 kg (v\u010d. baterie)<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Rozm\u011bry:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>965 x 2025 x 750 mm<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.9968%; border: none;\"><strong>Sv\u011btl\u00e1 v\u00fd\u0161ka:<\/strong><\/td>\n<td style=\"width: 61.0032%; border: none; text-align: right;\"><span>100 mm<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][et_pb_video src=&#8220;https:\/\/youtu.be\/-wPHSaz5l9g&#8220; _builder_version=&#8220;4.21.0&#8243; custom_margin=&#8220;15px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; border_width_all=&#8220;3px&#8220; border_color_all=&#8220;#fecc00&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\uf015 \u00davod \uf105 Produkty \uf105 Elektrick\u00e9 taha\u010de \uf105 Do 25t Elektrick\u00fd taha\u010d BULL 7E<div class=\"et_pb_module dsm_image_carousel dsm_image_carousel_0 dsm_image_carousel_arrow_outside dsm_image_carousel_arrow_mobile_outside \">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"swiper-container dsm_image_carousel_container  dsm_image_carousel_carousel\" dir=\"ltr\"data-effect=\"default\"\n\t\t\tdata-slider-effect-shadows=\"false\"\n\t\t\tdata-slider-effect-coverflow-rotate=\"30\"\n\t\t\tdata-slider-effect-coverflow-depth=\"0\"\n\t\t\tdata-loop=\"true\"\n\t\t\tdata-slide-to-show=\"1\"\n\t\t\tdata-slide-to-show-tablet=\"1\"\n\t\t\tdata-slide-to-show-phone=\"1\"\n\t\t\tdata-slide-to-scroll=\"1\"\n\t\t\tdata-slide-to-scroll-tablet=\"1\"\n\t\t\tdata-slide-to-scroll-phone=\"1\"\n\t\t\tdata-space-between=\"0\"\n\t\t\tdata-space-between-tablet=\"0\"\n\t\t\tdata-space-between-phone=\"0\"\n\t\t\tdata-slide-row=\"1\"\n\t\t\tdata-centered-slides=\"false\"\n\t\t\tdata-speed=\"1000\"\n\t\t\tdata-autoplay=\"true\"\n\t\t\tdata-autoplay-speed=\"3000\"\n\t\t\tdata-touch-move=\"true\"\n\t\t\tdata-grab=\"true\"\n\t\t\tdata-pause-on-hover=\"true\"\n\t\t\tdata-show-lightbox=\"true\"\n\t\t\tdata-lightbox-gallery=\"true\"\n\t\t\tdata-lightbox-caption=\"false\"\n\t\t\tdata-infinite-scrolling=\"false\"\n\t\t\tdata-slide-row-tablet=\"1\"\n\t\t\tdata-slide-row-phone=\"1\"\n\t\t\tdata-autoplay-viewport=80%\n\t\t\tdata-mousewheel=\"false\"\n\t\t\tdata-lazyload=\"false\"\n\t\t\tdata-type=\"carousel\"\n\t\t\tdata-slideshow-effect=\"default\"\n\t\t\tdata-slideshow-to-show=\"4\"\n\t\t\tdata-slideshow-to-show-tablet=\"4\"\n\t\t\tdata-slideshow-to-show-phone=\"\"\n\t\t\tdata-slider-orientation=\"horizontal\"\n\t\t\t\t\t\tdata-lightbox-title=\"false\"\n\n\t\t\t><div class=\"swiper-wrapper\"><div class=\"swiper-slide dsm_image_carousel_item\"><a class=\"dsm_image_carousel_lightbox\" href=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-sediciho-ridice-naklad-do-7-tun.jpg\" data-mfp-src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-sediciho-ridice-naklad-do-7-tun.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-sediciho-ridice-naklad-do-7-tun.jpg\" alt=\"taha\u010d pro sed\u00edc\u00edho \u0159idi\u010de a pro n\u00e1klad na kole\u010dk\u00e1ch do 7 tun, bull 7E\" title=\"elektricky-tahac-bull-7E-dec-pro-sediciho-ridice-naklad-do-7-tun\" width=\"702\" height=\"701\" data-dsm-image-description=\"\" srcset=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-sediciho-ridice-naklad-do-7-tun.jpg 702w, https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-sediciho-ridice-naklad-do-7-tun-480x479.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 702px, 100vw\" class=\" skip-lazy\" \/><\/a><\/div><div class=\"swiper-slide dsm_image_carousel_item\"><a class=\"dsm_image_carousel_lightbox\" href=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-tezky-naklad-do-7-tun.jpg\" data-mfp-src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-tezky-naklad-do-7-tun.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-tezky-naklad-do-7-tun.jpg\" alt=\"taha\u010d pro sed\u00edc\u00edho \u0159idi\u010de a pro n\u00e1klad na kole\u010dk\u00e1ch do 7 tun, bull 7E\" title=\"elektricky-tahac-bull-7E-dec-pro-tezky-naklad-do-7-tun\" width=\"501\" height=\"502\" data-dsm-image-description=\"\" srcset=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-tezky-naklad-do-7-tun.jpg 501w, https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-pro-tezky-naklad-do-7-tun-480x481.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 501px, 100vw\" class=\" skip-lazy\" \/><\/a><\/div><div class=\"swiper-slide dsm_image_carousel_item\"><a class=\"dsm_image_carousel_lightbox\" href=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-naklad-do-7-tun.jpg\" data-mfp-src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-naklad-do-7-tun.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-naklad-do-7-tun.jpg\" alt=\"taha\u010d pro sed\u00edc\u00edho \u0159idi\u010de a pro n\u00e1klad na kole\u010dk\u00e1ch do 7 tun, bull 7E\" title=\"elektricky-tahac-bull-7E-dec-s-kabinou-pro-naklad-do-7-tun\" width=\"502\" height=\"502\" data-dsm-image-description=\"\" srcset=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-naklad-do-7-tun.jpg 502w, https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-naklad-do-7-tun-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 502px, 100vw\" class=\" skip-lazy\" \/><\/a><\/div><div class=\"swiper-slide dsm_image_carousel_item\"><a class=\"dsm_image_carousel_lightbox\" href=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-sediciho-ridice.jpg\" data-mfp-src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-sediciho-ridice.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-sediciho-ridice.jpg\" alt=\"taha\u010d dec bull 7e s vyh\u0159\u00edvanou kabinou pro sed\u00edc\u00edho \u0159idi\u010de a pro n\u00e1klad do 7 tun\" title=\"elektricky-tahac-bull-7E-dec-s-kabinou-pro-sediciho-ridice\" width=\"502\" height=\"501\" data-dsm-image-description=\"\" srcset=\"https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-sediciho-ridice.jpg 502w, https:\/\/www.jklas.cz\/wp-content\/uploads\/2023\/07\/elektricky-tahac-bull-7E-dec-s-kabinou-pro-sediciho-ridice-480x479.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 502px, 100vw\" class=\" skip-lazy\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-button-prev swiper-arrow-button\" data-icon=\"4\"><\/div><div class=\"swiper-button-next swiper-arrow-button\" data-icon=\"5\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Z\u00e1kladn\u00ed informaceElektrick\u00fd taha\u010d pro sed\u00edc\u00edho \u0159idi\u010de BULL 7E slou\u017e\u00ed k manipulaci n\u00e1kladu a\u017e do 7 tun. Je v\u00fdkonn\u00fd, ergonomick\u00fd a n\u00edzko polo\u017een\u00fd pro snadn\u00e9 nastupov\u00e1n\u00ed\/vystupov\u00e1n\u00ed. Hod\u00ed se pro vnit\u0159n\u00ed i venkovn\u00ed pou\u017eit\u00ed. Taha\u010d lze vybavit \u0161irokou \u0161k\u00e1lou p\u0159\u00edslu\u0161enstv\u00ed \u2013 nap\u0159. bezp. osv\u011btlen\u00ed, kabina pro \u0159idi\u010de, st\u011bra\u010de a mnoho dal\u0161\u00edho (viz video). S konfigurac\u00ed stroje V\u00e1m r\u00e1di pom\u016f\u017eeme. Kabina m\u016f\u017ee b\u00fdt bu\u010f otev\u0159en\u00e1 (bez dve\u0159\u00ed) nebo lehk\u00e1 (PVC) nebo robustn\u00ed kovov\u00e1. Interaktivn\u00ed displej ukazuje stav baterie, rychlost apod. Taha\u010d je standardn\u011b vybaven trak\u010dn\u00ed bateri\u00ed, jej\u00ed\u017e v\u00fdm\u011bna m\u016f\u017ee b\u00fdt provedena vertik\u00e1ln\u011b i horizont\u00e1ln\u011b. Pro v\u00edce informac\u00ed o taha\u010di, n\u00e1s pros\u00edm kontaktujte.Dopl\u0148kov\u00e1 v\u00fdbava (na p\u0159\u00e1n\u00ed): kabina bez dve\u0159\u00ed (otev\u0159en\u00e1), kabina PVC, kabina kovov\u00e1, vyt\u00e1p\u011bn\u00ed kabiny, \u010deln\u00ed sklo, st\u011bra\u010de, zp\u011btn\u00e1 zrc\u00e1tka, bezp. maj\u00e1k, modr\u00e9 sv\u011btlo, nezna\u010d\u00edc\u00ed kola, tla\u010d\u00edtka pro manu\u00e1ln\u00ed pojezd vp\u0159ed\/vzad, set pro v\u00fdm\u011bnu baterie, a dal\u0161\u00ed&#8230;Vertik\u00e1ln\u00ed i horizont\u00e1ln\u00ed v\u00fdm\u011bna bateriePro vnit\u0159n\u00ed i venkovn\u00ed pou\u017eit\u00edPrezentace &#8211; elektrick\u00e9 taha\u010de do 25t (CZ) \u201eProhl\u00e9dn\u011bte si PDF prezentaci na\u0161ich taha\u010d\u016f \u2013 obsahuje p\u0159ehled model\u016f, fotky a dal\u0161\u00ed u\u017eite\u010dn\u00e9 informace.\u201c &#8222;P\u0159ejete si zaslat cenovou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":39450,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-40837","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/pages\/40837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/comments?post=40837"}],"version-history":[{"count":6,"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/pages\/40837\/revisions"}],"predecessor-version":[{"id":40952,"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/pages\/40837\/revisions\/40952"}],"up":[{"embeddable":true,"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/pages\/39450"}],"wp:attachment":[{"href":"https:\/\/www.jklas.cz\/sk\/wp-json\/wp\/v2\/media?parent=40837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}